{"id":4643,"date":"2023-05-16T22:48:15","date_gmt":"2023-05-16T20:48:15","guid":{"rendered":"https:\/\/www.lycee-valin.fr\/RJVALIN\/?p=4643"},"modified":"2023-05-17T14:22:33","modified_gmt":"2023-05-17T12:22:33","slug":"les-eleves-de-premiere-lvb-espagnol-aux-bassins-de-lumieres-a-bordeaux","status":"publish","type":"post","link":"https:\/\/www.lycee-valin.fr\/RJVALIN\/les-eleves-de-premiere-lvb-espagnol-aux-bassins-de-lumieres-a-bordeaux\/","title":{"rendered":"Exp\u00e9riences immersives des \u00e9l\u00e8ves de premi\u00e8re LVB espagnol aux Bassins des lumi\u00e8res \u00e0 Bordeaux"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lumi\u00e8res catalanes.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le 04 mai 2023, les \u00e9l\u00e8ves de premi\u00e8res LVB espagnol sont all\u00e9s aux Bassins des lumi\u00e8res de Bordeaux pour d\u00e9couvrir deux expositions immersives.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le programme long \u00ab Dal\u00ed, l\u2019\u00e9nigme sans fin \u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 travers un parcours th\u00e9matique, les \u00e9l\u00e8ves se sont promen\u00e9s dans des paysages au c\u0153ur des \u0153uvres de l\u2019artiste catalan.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les toiles de Salvador Dal\u00ed se sont dessin\u00e9es sur les murs au son des musiques du groupe l\u00e9gendaire Pink Floyd.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2023\/05\/Dali.png\" alt=\"\" class=\"wp-image-4648\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2023\/05\/Dali.png 640w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2023\/05\/Dali-300x225.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Afin de compl\u00e9ter cette visite libre, les \u00e9l\u00e8ves ont r\u00e9pondu \u00e0 un quiz sur la vie et l\u2019\u0153uvre de Dal\u00ed. Un digipad r\u00e9alis\u00e9 par les professeurs d\u2019espagnol \u00e9tait accessible via un QR code pour les guider dans ce travail.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le programme court \u00ab Gaud\u00ed, architecte de l\u2019imaginaire \u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9couverte d\u2019un autre artiste catalan et de ses r\u00e9alisations architecturales aujourd\u2019hui class\u00e9es au patrimoine de l\u2019UNESCO.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2023\/05\/Gaudi-1.png\" alt=\"\" class=\"wp-image-4649\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2023\/05\/Gaudi-1.png 640w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2023\/05\/Gaudi-1-300x225.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Merci \u00e0 Valin Cultures pour son don qui a permis la gratuit\u00e9 de cette sortie pour les \u00e9l\u00e8ves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aur\u00e9lia Sennane&nbsp;<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Merci \u00e0 Valin Cultures pour son don qui a permis la gratuit\u00e9 de cette sortie pour les \u00e9l\u00e8ves. Aur\u00e9lia Sennane&nbsp;<\/p>\n","protected":false},"author":44,"featured_media":4644,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83,82],"tags":[],"class_list":["post-4643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espagnol","category-sortie-pedagogique"],"_links":{"self":[{"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/posts\/4643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/comments?post=4643"}],"version-history":[{"count":4,"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/posts\/4643\/revisions"}],"predecessor-version":[{"id":4650,"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/posts\/4643\/revisions\/4650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/media\/4644"}],"wp:attachment":[{"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/media?parent=4643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/categories?post=4643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/tags?post=4643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}