{"id":3138,"date":"2022-11-24T13:36:21","date_gmt":"2022-11-24T12:36:21","guid":{"rendered":"https:\/\/www.lycee-valin.fr\/RJVALIN\/?p=3138"},"modified":"2022-11-25T10:49:38","modified_gmt":"2022-11-25T09:49:38","slug":"fete-de-la-science-2022","status":"publish","type":"post","link":"https:\/\/www.lycee-valin.fr\/RJVALIN\/fete-de-la-science-2022\/","title":{"rendered":"F\u00eate de la science 2022"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"473\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084233-2-1024x473.jpg\" alt=\"\" class=\"wp-image-3263\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084233-2-1024x473.jpg 1024w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084233-2-300x139.jpg 300w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084233-2-768x355.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084233-2-1536x710.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084233-2-2048x946.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#a818ca\">F\u00eate de la Science anim\u00e9e au lyc\u00e9e Valin, mercredi 12 octobre 2022<\/h2>\n\n\n\n<p><strong>Mercredi 12 octobre 2022<\/strong> a eu lieu la 3\u00e8me \u00e9dition de la <strong>f\u00eate de la Science<\/strong> au<strong> lyc\u00e9e VALIN<\/strong>, organis\u00e9e par l\u2019\u00e9quipe de biotechnologie, en partenariat avec l&#8217;Universit\u00e9 de La Rochelle.<\/p>\n\n\n\n<p class=\"has-text-color\" style=\"color:#0593a3\">C&#8217;est avec plaisir que nous avons accueilli : <em>\u00e9l\u00e8ves, professeurs, personnels, famille et amis<\/em>, pour partager le plaisir des couleurs, th\u00e8me de l&#8217;\u00e9dition.<\/p>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-ad2f72ca wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_133636-768x1024.jpg\" alt=\"\" class=\"wp-image-3207\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_133636-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_133636-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_133636-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_133636-1536x2048.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_133636-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132343-768x1024.jpg\" alt=\"\" class=\"wp-image-3209\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132343-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132343-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132343-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132343-1536x2048.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132343-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132429-1-768x1024.jpg\" alt=\"\" class=\"wp-image-3212\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132429-1-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132429-1-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132429-1-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132429-1-1536x2048.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132429-1-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_104650-768x1024.jpg\" alt=\"\" class=\"wp-image-3210\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_104650-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_104650-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_104650-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_104650-1536x2048.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_104650-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<p class=\"has-cool-to-warm-spectrum-gradient-background has-text-color has-background\" style=\"color:#f0b029;font-size:20px\"><strong>Le plaisir des couleurs en biotechnologies<\/strong><\/p>\n\n\n\n<p>Plusieurs classes se sont succ\u00e9d\u00e9es toute la matin\u00e9e et en d\u00e9but d\u2019apr\u00e8s-midi, pour jouer avec nous&nbsp;: des <strong>bo\u00eetes \u00e0 bonbons cadenass\u00e9es<\/strong> et donc des <strong>codes \u00e0 trouver<\/strong>&nbsp;!<\/p>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-ad2f72ca wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163037-768x1024.jpg\" alt=\"\" class=\"wp-image-3235\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163037-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163037-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163037-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163037-1536x2048.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163037-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163015-768x1024.jpg\" alt=\"\" class=\"wp-image-3225\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163015-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163015-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163015-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163015-1536x2048.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163015-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163104-1-768x1024.jpg\" alt=\"\" class=\"wp-image-3240\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163104-1-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163104-1-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163104-1-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163104-1-1536x2048.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221011163104-1-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-ad2f72ca wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"834\" height=\"1024\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_094453_136-834x1024.jpg\" alt=\"\" class=\"wp-image-3246\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_094453_136-834x1024.jpg 834w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_094453_136-244x300.jpg 244w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_094453_136-768x943.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_094453_136-1252x1536.jpg 1252w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_094453_136-1669x2048.jpg 1669w\" sizes=\"(max-width: 834px) 100vw, 834px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012081829-768x1024.jpg\" alt=\"\" class=\"wp-image-3244\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012081829-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012081829-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012081829-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012081829-1536x2048.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012081829-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012104342-768x1024.jpg\" alt=\"\" class=\"wp-image-3243\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012104342-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012104342-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012104342-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012104342-1536x2048.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012104342-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<p class=\"has-electric-grass-gradient-background has-background\">A la d\u00e9couverte du code g\u00e9n\u00e9tique, de la spiruline, de la chromatographie de colorants alimentaires en passant par les milieux chromog\u00e8nes et le groupage sanguin, il y en avait pour toutes les couleurs cette ann\u00e9e. Il n\u2019y a pas que des \u00e9l\u00e8ves qui ont profit\u00e9 de la f\u00eate&nbsp;: parents, enseignants, personnels et personnes ext\u00e9rieures au lyc\u00e9e Valin, gr\u00e2ce au partenariat avec l\u2019Universit\u00e9 de La Rochelle.<\/p>\n\n\n\n<p>La galerie d&#8217;images<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"473\" data-id=\"3227\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_083335-1024x473.jpg\" alt=\"\" class=\"wp-image-3227\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_083335-1024x473.jpg 1024w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_083335-300x139.jpg 300w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_083335-768x355.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_083335-1536x710.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_083335-2048x946.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"473\" data-id=\"3230\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084101-1024x473.jpg\" alt=\"\" class=\"wp-image-3230\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084101-1024x473.jpg 1024w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084101-300x139.jpg 300w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084101-768x355.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084101-1536x710.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084101-2048x946.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"473\" data-id=\"3232\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084112-1024x473.jpg\" alt=\"\" class=\"wp-image-3232\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084112-1024x473.jpg 1024w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084112-300x139.jpg 300w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084112-768x355.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084112-1536x710.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084112-2048x946.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"473\" data-id=\"3231\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084117-1024x473.jpg\" alt=\"\" class=\"wp-image-3231\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084117-1024x473.jpg 1024w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084117-300x139.jpg 300w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084117-768x355.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084117-1536x710.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084117-2048x946.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"473\" height=\"1024\" data-id=\"3233\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084130-473x1024.jpg\" alt=\"\" class=\"wp-image-3233\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084130-473x1024.jpg 473w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084130-139x300.jpg 139w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084130-768x1662.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084130-710x1536.jpg 710w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084130-946x2048.jpg 946w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084130-scaled.jpg 1183w\" sizes=\"(max-width: 473px) 100vw, 473px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"473\" data-id=\"3226\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084233-1-1024x473.jpg\" alt=\"\" class=\"wp-image-3226\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084233-1-1024x473.jpg 1024w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084233-1-300x139.jpg 300w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084233-1-768x355.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084233-1-1536x710.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_084233-1-2048x946.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"473\" height=\"1024\" data-id=\"3229\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091042-473x1024.jpg\" alt=\"\" class=\"wp-image-3229\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091042-473x1024.jpg 473w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091042-139x300.jpg 139w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091042-768x1662.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091042-710x1536.jpg 710w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091042-946x2048.jpg 946w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091042-scaled.jpg 1183w\" sizes=\"(max-width: 473px) 100vw, 473px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"473\" data-id=\"3234\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091334-1024x473.jpg\" alt=\"\" class=\"wp-image-3234\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091334-1024x473.jpg 1024w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091334-300x139.jpg 300w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091334-768x355.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091334-1536x710.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091334-2048x946.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"473\" data-id=\"3228\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091339-1024x473.jpg\" alt=\"\" class=\"wp-image-3228\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091339-1024x473.jpg 1024w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091339-300x139.jpg 300w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091339-768x355.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091339-1536x710.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_091339-2048x946.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3219\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_104636-768x1024.jpg\" alt=\"\" class=\"wp-image-3219\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_104636-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_104636-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_104636-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_104636-1536x2048.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_104636-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3223\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132349-768x1024.jpg\" alt=\"\" class=\"wp-image-3223\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132349-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132349-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132349-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132349-1536x2048.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132349-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3222\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132405-768x1024.jpg\" alt=\"\" class=\"wp-image-3222\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132405-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132405-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132405-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132405-1536x2048.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_132405-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"473\" height=\"1024\" data-id=\"3241\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_090330-473x1024.jpg\" alt=\"\" class=\"wp-image-3241\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_090330-473x1024.jpg 473w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_090330-139x300.jpg 139w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_090330-768x1662.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_090330-710x1536.jpg 710w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_090330-946x2048.jpg 946w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_090330-scaled.jpg 1183w\" sizes=\"(max-width: 473px) 100vw, 473px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3218\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_152126-768x1024.jpg\" alt=\"\" class=\"wp-image-3218\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_152126-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_152126-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_152126-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_152126-1536x2048.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221012_152126-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"3215\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_084547_477-576x1024.jpg\" alt=\"\" class=\"wp-image-3215\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_084547_477-576x1024.jpg 576w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_084547_477-169x300.jpg 169w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_084547_477-768x1365.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_084547_477-864x1536.jpg 864w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_084547_477.jpg 1080w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"3216\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_104009_208-576x1024.jpg\" alt=\"\" class=\"wp-image-3216\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_104009_208-576x1024.jpg 576w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_104009_208-169x300.jpg 169w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_104009_208-768x1365.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_104009_208-864x1536.jpg 864w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG_20221012_104009_208.jpg 1080w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" data-id=\"3287\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134837-edited-2-scaled.jpg\" alt=\"\" class=\"wp-image-3287\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134837-edited-2-scaled.jpg 1920w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134837-edited-2-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134837-edited-2-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134837-edited-2-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134837-edited-2-1536x2048.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"3220\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134855-1024x768.jpg\" alt=\"\" class=\"wp-image-3220\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134855-1024x768.jpg 1024w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134855-300x225.jpg 300w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134855-768x576.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134855-1536x1152.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134855-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"3224\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134908-1024x768.jpg\" alt=\"\" class=\"wp-image-3224\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134908-1024x768.jpg 1024w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134908-300x225.jpg 300w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134908-768x576.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134908-1536x1152.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134908-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"3221\" src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134958-768x1024.jpg\" alt=\"\" class=\"wp-image-3221\" srcset=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134958-768x1024.jpg 768w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134958-225x300.jpg 225w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134958-1152x1536.jpg 1152w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134958-1536x2048.jpg 1536w, https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/IMG20221012134958-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Lien Vid\u00e9o<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"480\" style=\"aspect-ratio: 640 \/ 480;\" width=\"640\" controls src=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-content\/uploads\/2022\/11\/20221018_195746_75290105391224.mp4\"><\/video><\/figure>\n\n\n\n<p>Merci \u00e0 Christian GOICHON, qui coordonne l\u2019\u00e9v\u00e8nement, d\u2019\u00eatre pass\u00e9 nous voir, ainsi qu\u2019\u00e0 Alexandre Quentin pour ces photos.<\/p>\n\n\n\n<p>Merci \u00e0 tous les curieux d\u2019\u00eatre pass\u00e9 nous voir. Et au plaisir de se retrouver l\u2019ann\u00e9e prochaine, pour de nouvelles exp\u00e9riences. Je te tenais \u00e0 remercier vivement mes coll\u00e8gues et aux techniciens, pour le temps pass\u00e9 depuis 3 ans \u00e0 la tenue de cet \u00e9v\u00e8nement, pour leur investissement fid\u00e8le, et une mention particuli\u00e8re cette ann\u00e9e pour leur <strong>grande cr\u00e9ativit\u00e9<\/strong>, haute en couleurs&nbsp;!!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00eate de la Science anim\u00e9e au lyc\u00e9e Valin, mercredi 12 octobre 2022 Mercredi 12 octobre 2022 a eu lieu la 3\u00e8me \u00e9dition de la f\u00eate de la Science au lyc\u00e9e VALIN, organis\u00e9e par l\u2019\u00e9quipe de <a class=\"more-link\" href=\"https:\/\/www.lycee-valin.fr\/RJVALIN\/fete-de-la-science-2022\/\">Lire plus &#8230;<\/a><\/p>\n","protected":false},"author":40,"featured_media":3205,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68,1],"tags":[40,69,24],"class_list":["post-3138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biotechnologie","category-non-classe","tag-biotechnologies","tag-fete-de-la-science","tag-stl"],"_links":{"self":[{"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/posts\/3138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/comments?post=3138"}],"version-history":[{"count":17,"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/posts\/3138\/revisions"}],"predecessor-version":[{"id":3289,"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/posts\/3138\/revisions\/3289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/media\/3205"}],"wp:attachment":[{"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/media?parent=3138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/categories?post=3138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lycee-valin.fr\/RJVALIN\/wp-json\/wp\/v2\/tags?post=3138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}